{"id":1134,"date":"2021-11-06T18:10:10","date_gmt":"2021-11-06T17:10:10","guid":{"rendered":"https:\/\/siedlerverein-wittgensdorf.de\/?p=1134"},"modified":"2021-11-21T20:55:57","modified_gmt":"2021-11-21T19:55:57","slug":"der-lebendige-adventskalender-bei-uns-zu-gast","status":"publish","type":"post","link":"https:\/\/siedlerverein-wittgensdorf.de\/index.php\/2021\/11\/06\/der-lebendige-adventskalender-bei-uns-zu-gast\/","title":{"rendered":"Der lebendige Adventskalender &#8211; ABGESAGT"},"content":{"rendered":"<p><span style=\"color: #ff0000;\">schade.. auch diese Veranstaltung m\u00fcssen wir leider absagen! Wir bitten um Euer Verst\u00e4ndnis<\/span><\/p>\n<p>&nbsp;<\/p>\n<hr \/>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><strong>Wir freuen uns auf den Samstag, 11.12.2021.<\/strong><\/p>\n<p style=\"text-align: left;\">Von 17-19Uhr findet der lebendige Adventskalender Wittgensdorf bei uns am Siedlerheim statt.<\/p>\n<p style=\"text-align: left;\">Merkt Euch schonmal den Termin &amp; dr\u00fcckt die Daumen, dass uns keine Einschr\u00e4nkung einen Strich durch die Rechnung macht.<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-1135 size-full alignright\" src=\"https:\/\/siedlerverein-wittgensdorf.de\/wp-content\/uploads\/2021\/11\/Weihnachtskugel.jpg\" alt=\"\" width=\"332\" height=\"181\" srcset=\"https:\/\/siedlerverein-wittgensdorf.de\/wp-content\/uploads\/2021\/11\/Weihnachtskugel.jpg 332w, https:\/\/siedlerverein-wittgensdorf.de\/wp-content\/uploads\/2021\/11\/Weihnachtskugel-300x164.jpg 300w\" sizes=\"(max-width: 332px) 100vw, 332px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>schade.. auch diese Veranstaltung m\u00fcssen wir leider absagen! Wir bitten um Euer Verst\u00e4ndnis &nbsp; &nbsp; Wir freuen uns auf den Samstag, 11.12.2021. Von 17-19Uhr findet der lebendige Adventskalender Wittgensdorf bei uns am Siedlerheim statt. Merkt Euch schonmal den Termin &amp; dr\u00fcckt die Daumen, dass uns keine Einschr\u00e4nkung einen Strich durch die Rechnung macht.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"image","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1134","post","type-post","status-publish","format-image","hentry","category-allgemein","post_format-post-format-image"],"_links":{"self":[{"href":"https:\/\/siedlerverein-wittgensdorf.de\/index.php\/wp-json\/wp\/v2\/posts\/1134"}],"collection":[{"href":"https:\/\/siedlerverein-wittgensdorf.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/siedlerverein-wittgensdorf.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/siedlerverein-wittgensdorf.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/siedlerverein-wittgensdorf.de\/index.php\/wp-json\/wp\/v2\/comments?post=1134"}],"version-history":[{"count":5,"href":"https:\/\/siedlerverein-wittgensdorf.de\/index.php\/wp-json\/wp\/v2\/posts\/1134\/revisions"}],"predecessor-version":[{"id":1144,"href":"https:\/\/siedlerverein-wittgensdorf.de\/index.php\/wp-json\/wp\/v2\/posts\/1134\/revisions\/1144"}],"wp:attachment":[{"href":"https:\/\/siedlerverein-wittgensdorf.de\/index.php\/wp-json\/wp\/v2\/media?parent=1134"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/siedlerverein-wittgensdorf.de\/index.php\/wp-json\/wp\/v2\/categories?post=1134"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/siedlerverein-wittgensdorf.de\/index.php\/wp-json\/wp\/v2\/tags?post=1134"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}